{"id":16882,"date":"2026-01-09T15:19:53","date_gmt":"2026-01-09T23:19:53","guid":{"rendered":"https:\/\/www.dc16iupat.org\/?p=16882"},"modified":"2026-01-09T15:19:55","modified_gmt":"2026-01-09T23:19:55","slug":"contract-and-pension-2","status":"publish","type":"post","link":"https:\/\/www.dc16iupat.org\/es\/contract-and-pension-2\/","title":{"rendered":"\u00a1Contrato y pensi\u00f3n!"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"659\" src=\"https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-10.png\" alt=\"\" class=\"wp-image-16884\" srcset=\"https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-10.png 800w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-10-300x247.png 300w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-10-768x633.png 768w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-10-15x12.png 15w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Bienvenidos de nuevo y \u00a1Feliz A\u00f1o Nuevo a todos! Esperamos que hayan disfrutado de las fiestas y que hayan tenido la oportunidad de pasar tiempo de calidad con sus seres queridos. Como ya saben, los contratos de pintores y yeseros vencer\u00e1n en junio. El Local 3 envi\u00f3 un mensaje a trav\u00e9s de Unite el martes con un cuestionario solicitando su opini\u00f3n sobre lo que les gustar\u00eda ver en el pr\u00f3ximo contrato. Les pedimos que dediquen unos minutos a darnos su opini\u00f3n. Presentaremos toda la informaci\u00f3n recopilada al Secretario Tesorero Williams para las negociaciones. Tambi\u00e9n queremos agradecer a todos los que ya han respondido. Si no han recibido el mensaje de texto, comun\u00edquense con su representante sindical. Mientras nos preparamos para la expiraci\u00f3n de nuestros contratos, les recomendamos que empiecen a ahorrar dinero por si acaso fuera necesaria una huelga. Recuerden que todas las voces importan y que juntos somos m\u00e1s fuertes. \u00a1En solidaridad!...<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"531\" src=\"https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-9.png\" alt=\"\" class=\"wp-image-16883\" srcset=\"https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-9.png 885w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-9-300x180.png 300w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-9-768x461.png 768w, https:\/\/www.dc16iupat.org\/wp-content\/uploads\/2026\/01\/image-9-18x12.png 18w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/figure>\n\n\n\n<p>\u00bfSab\u00eda que para poder recibir su pensi\u00f3n primero debe cumplir con el requisito de antig\u00fcedad? La antig\u00fcedad es el proceso mediante el cual se obtiene la titularidad completa de los beneficios proporcionados por el empleador. Para obtener la antig\u00fcedad en su pensi\u00f3n de pintores o yeseros, debe acumular 5 cr\u00e9ditos completos. Los cr\u00e9ditos se obtienen en funci\u00f3n del n\u00famero de horas trabajadas durante un a\u00f1o calendario. A continuaci\u00f3n, se muestra el detalle.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\">0-399hrs= 0 credits     400-699hrs= \u00bd credit<\/p>\n\n\n\n<p class=\"has-text-align-center\">700-999hrs= \u00be credit       1000+hrs= 1 credit\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Visite el sitio web del Fondo de Pensiones para Pintores y Empapeladores del \u00c1rea de la Bah\u00eda y cree una cuenta en https:\/\/bayareapainterstrust.org\/ para consultar sus horas trabajadas y comprobar si tiene derecho a la pensi\u00f3n.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Welcome back and Happy New Year to everyone. We hope you enjoyed the holidays and had the opportunity to spend some quality time with the people you love. As you all should know, both the contracts for Painters and Tapers will be expiring in June. Local 3 sent out a Unite message on Tuesday with [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16882","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"jetpack_featured_media_url":"","post_image":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/16882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/comments?post=16882"}],"version-history":[{"count":0,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/16882\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/media?parent=16882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/categories?post=16882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/tags?post=16882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}