{"id":15692,"date":"2025-07-25T11:29:35","date_gmt":"2025-07-25T18:29:35","guid":{"rendered":"https:\/\/www.dc16iupat.org\/?p=15692"},"modified":"2025-07-28T11:29:48","modified_gmt":"2025-07-28T18:29:48","slug":"we-still-need-floor-layers","status":"publish","type":"post","link":"https:\/\/www.dc16iupat.org\/es\/we-still-need-floor-layers\/","title":{"rendered":"Todav\u00eda necesitamos colocadores de pisos"},"content":{"rendered":"<p>Hermanos y hermanas, espero que esto los encuentre bien.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nuestro sindicato local busca personas trabajadoras para instalar alfombras. Si usted o alguien que conoce est\u00e1 sin trabajo, este es un excelente momento para unirse.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ser parte de nuestro sindicato no se trata solo de tener un trabajo, sino de construir un futuro. Los afiliados al sindicato disfrutan de excelentes beneficios, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gran salario por hora<\/strong><\/li>\n\n\n\n<li><strong>Seguro m\u00e9dico<\/strong><\/li>\n\n\n\n<li><strong>Planes de jubilaci\u00f3n<\/strong><\/li>\n\n\n\n<li><strong>Formaci\u00f3n y desarrollo de habilidades<\/strong><\/li>\n\n\n\n<li><strong>Apoyo de una comunidad fuerte<\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Trabajamos juntos para garantizar que todos se mantengan seguros, ocupados y respetados en el trabajo. Cuantos m\u00e1s buenos miembros tengamos, m\u00e1s fuerte ser\u00e1 nuestro sindicato.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Si conoces a alguien que est\u00e9 listo para trabajar, env\u00edalo. Crezcamos juntos y hagamos que nuestro Local siga avanzando.<\/p>\n\n\n\n<p>\u00a1Mantente activo, mantente en contacto, mantente seguro y nunca dejes de luchar por un futuro justo!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Si necesita ayuda de mi parte, no dude en ponerse en contacto conmigo.<\/p>\n\n\n\n<p>Mi n\u00famero de tel\u00e9fono es: (702) 403-0700<\/p>\n\n\n\n<p>Correo electr\u00f3nico: <a href=\"mailto:gustavo@dc16.us\">gustavo@dc16.us<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXeOla3brik8FKLSJw-_WKWbCaas0QL-XbgIMwz47Ptoi6An2WkACM8dwgmISAAfS_8B-3Z37wFp1fwTxrzg9qgjY5xV9g5DX0FHGT7VroMSMGeYG-0xOtbMdmxdzqmjiCEQ-S2bmgslDIkGtrMc1Q?key=OFTeze2F538qFh2Xj_vxMw\" alt=\"A group of men in safety vests working on a floorAI-generated content may be incorrect.\"\/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Brothers and Sisters, \ufeffI hope this finds you well. Our Local Union is looking for hardworking people to become carpet installers. If you or someone you know is out of work, now is a great time to join. Being part of our union isn\u2019t just about having a job\u2014it\u2019s about building a future. Union members [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15692","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"jetpack_featured_media_url":"","post_image":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/15692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/comments?post=15692"}],"version-history":[{"count":0,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/15692\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/media?parent=15692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/categories?post=15692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/tags?post=15692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}