{"id":11407,"date":"2023-09-08T16:27:55","date_gmt":"2023-09-08T23:27:55","guid":{"rendered":"https:\/\/www.dc16iupat.org\/?p=11407"},"modified":"2023-09-08T16:27:56","modified_gmt":"2023-09-08T23:27:56","slug":"whats-new-2","status":"publish","type":"post","link":"https:\/\/www.dc16iupat.org\/es\/whats-new-2\/","title":{"rendered":"\u00bf\u00bf\u00bf\u00bf\u00bf\u00bf\u00bfQu\u00e9 hay de nuevo???????"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Hermanos y Hermanas,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo se ha ralentizado ya que la mayor\u00eda de los proyectos escolares est\u00e1n terminados. La lista de desempleados a d\u00eda de hoy (7\/9\/23) tiene 8 miembros en la lista, 4 oficiales y 4 aprendices. Si est\u00e1 solicitando desempleo, debe estar en la lista de desempleados; si el Departamento de Desarrollo del Empleo (EDD) llama y usted no est\u00e1 en la lista, negar\u00e1n su reclamo de desempleo. Los aprendices deben estar en la lista seg\u00fan su acuerdo de aprendizaje y estar disponibles para una asignaci\u00f3n DAS-142 si se les llama. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me gustar\u00eda pedirles a todos los miembros y sus familias que consideren participar en la Caminata Anual Avanzando Contra el C\u00e1ncer de Mama el 15 de octubre de 2023 en Sac State. Los locales 1237, 767 y 487 han participado durante a\u00f1os y necesitamos que m\u00e1s personas se unan a nosotros por una causa que vale la pena. La mayor\u00eda de nosotros conocemos a alguien que tiene o tuvo c\u00e1ncer de mama y, con suerte, gan\u00f3 la lucha. Esta es una oportunidad para caminar en nombre de quienes son personas y ayudar a crear conciencia. Los 3 locales donan a la causa y registrarse es gratis. He incluido el enlace para su comodidad. Espero que t\u00fa y los tuyos os un\u00e1is a nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/secure.acsevents.org\/site\/STR?pg=entry&amp;fr_id=105657\">https:\/\/secure.acsevents.org\/site\/STR?pg=entry&amp;fr_id=105657<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fraternalmente,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Randy Rojas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Representante Empresarial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DC16\/LU1237<\/p>","protected":false},"excerpt":{"rendered":"<p>Brothers and Sisters, Work has slowed down since most of the school projects are complete. The out-of-work list as of today (9\/7\/23) has 8 members on the list, 4 journeymen and 4 apprentices. If you are filing for unemployment you need to be on the out-of-work list, if the Employment Development Department (EDD) calls and [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11407","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"jetpack_featured_media_url":"","post_image":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/11407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/comments?post=11407"}],"version-history":[{"count":0,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/posts\/11407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/media?parent=11407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/categories?post=11407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dc16iupat.org\/es\/wp-json\/wp\/v2\/tags?post=11407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}